{"id":2488,"date":"2024-02-09T10:44:08","date_gmt":"2024-02-09T10:44:08","guid":{"rendered":"https:\/\/florentiadent.com\/?page_id=2488"},"modified":"2024-02-28T18:28:24","modified_gmt":"2024-02-28T18:28:24","slug":"impianti-dentali","status":"publish","type":"page","link":"https:\/\/florentiadent.com\/en\/impianti-dentali\/","title":{"rendered":"Dental Implants"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2488\" class=\"elementor elementor-2488\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e8cc24f e-flex e-con-boxed e-con e-parent\" data-id=\"e8cc24f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\r\n\t\t<div class=\"elementor-element elementor-element-f2ca1dc elementor-widget__width-inherit elementor-widget-tablet__width-inherit elementor-widget elementor-widget-mediaxsectiontitle\" data-id=\"f2ca1dc\" data-element_type=\"widget\" data-widget_type=\"mediaxsectiontitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"title-area text-center\">\r\n\t\t\t<span class=\"sub-title\"><img decoding=\"async\" src=\"https:\/\/florentiadent.com\/wp-content\/plugins\/mediax-core\/assets\/img\/title_icon.svg\" alt=\"Shape\">IMPIANTI DENTALI<\/span>\t\t<\/div>\r\n\r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-418360b1 e-con-full e-flex e-con e-parent\" data-id=\"418360b1\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-38970a80 e-con-full sidebar-area e-flex e-con e-child\" data-id=\"38970a80\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-fa069f5 e-con-full e-flex e-con e-child\" data-id=\"fa069f5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-66c871cb elementor-widget elementor-widget-mediaxservicelist\" data-id=\"66c871cb\" data-element_type=\"widget\" data-widget_type=\"mediaxservicelist.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"widget widget_categories\"><h3 class=\"widget_title\">All Services<\/h3><ul><li><a href=\"https:\/\/florentiadent.com\/en\/impianti-dentali\/\">Dental Implants<\/a><\/li><li><a href=\"https:\/\/florentiadent.com\/en\/corone-dentali\/\">Dental Crowns<\/a><\/li><li><a href=\"https:\/\/florentiadent.com\/en\/protesi-dentale\/\">Dental prosthesis<\/a><\/li><li><a href=\"https:\/\/florentiadent.com\/en\/allineatori-invisalign\/\">Invisalign Aligners<\/a><\/li><li><a href=\"https:\/\/florentiadent.com\/en\/chirurgia-orale-e-maxillo-facciale\/\">Oral and Maxillofacial Surgery<\/a><\/li><li><a href=\"https:\/\/florentiadent.com\/en\/estetica-facciale\/\">Aesthetics<\/a><\/li><\/ul><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7a0abe elementor-widget__width-initial elementor-widget elementor-widget-mediaxcontactform\" data-id=\"d7a0abe\" data-element_type=\"widget\" data-widget_type=\"mediaxcontactform.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"row justify-content-center text-center\"><div class=\"col-xl-9\"><div class=\"title-area\"><h2 class=\"sec-title mb-0\">We Create Beautiful Smiles<\/h2><p class=\"sec-text\">Fill out the form below for a free quote!<\/p><\/div><\/div><\/div><div class=\"appointment-form2 bg\"><h4 class=\"form-title title\">Book an appointment<\/h4>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1877-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/2488#wpcf7-f1877-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/pages\/2488#wpcf7-f1877-o1\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"1877\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.9.3\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1877-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<div class=\"row\">\n    <div class=\"form-group col-12\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"text-657\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your Name\" value=\"\" type=\"text\" name=\"text-657\" \/><\/span>\n        <i class=\"fal fa-user\"><\/i>\n    <\/div>\n    <div class=\"form-group col-12\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email-840\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email form-control\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your Email\" value=\"\" type=\"email\" name=\"email-840\" \/><\/span>\n        <i class=\"fal fa-envelope\"><\/i>\n    <\/div>\n    <div class=\"form-group col-12\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"number-159\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-required wpcf7-validates-as-number form-control\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Telephone number\" value=\"\" type=\"number\" name=\"number-159\" \/><\/span>\n        <i class=\"fal fa-phone\"><\/i>\n    <\/div>\n    <div class=\"form-group col-12\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"menu-721\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required form-select nice-select\" id=\"subject\" aria-required=\"true\" aria-invalid=\"false\" name=\"menu-721\"><option value=\"Scegli Oggetto\">Choose Object<\/option><option value=\"Ottieni un preventivo\">Get a quote<\/option><option value=\"Consulenza Gratuita\">Free Consultation<\/option><\/select><\/span>\n        <i class=\"fal fa-chevron-down\"><\/i>\n    <\/div>\n    <div class=\"form-group col-12\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-839\"><textarea cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required form-control\" id=\"message\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Type appointment note...\" name=\"textarea-839\"><\/textarea><\/span>\n        <i class=\"fal fa-pencil\"><\/i>\n    <\/div>\n    <div class=\"form-btn col-12\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"Impostailpunteggiodelquiz\"><label><span class=\"wpcf7-quiz-label\">2+8=?<\/span> <input size=\"40\" class=\"wpcf7-form-control wpcf7-quiz\" autocomplete=\"off\" aria-required=\"true\" aria-invalid=\"false\" type=\"text\" name=\"Impostailpunteggiodelquiz\" \/><\/label><input type=\"hidden\" name=\"_wpcf7_quiz_answer_Impostailpunteggiodelquiz\" value=\"d0f4210e4737e1c716c04f36b802d731\" \/><\/span>\n        <button class=\"th-btn btn-fw wpcf7\">SEND YOUR REQUEST<\/button>\n    <\/div>\n<\/div>\n<p class=\"form-messages mb-0 mt-3\"><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n<\/div>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-191431f7 e-con-full e-flex e-con e-child\" data-id=\"191431f7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-75be8a00 elementor-widget elementor-widget-image\" data-id=\"75be8a00\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 18-04-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"350\" src=\"https:\/\/florentiadent.com\/wp-content\/uploads\/2024\/02\/Dental-Implants-3.png\" class=\"attachment-full size-full wp-image-2191\" alt=\"\" srcset=\"https:\/\/florentiadent.com\/wp-content\/uploads\/2024\/02\/Dental-Implants-3.png 800w, https:\/\/florentiadent.com\/wp-content\/uploads\/2024\/02\/Dental-Implants-3-300x131.png 300w, https:\/\/florentiadent.com\/wp-content\/uploads\/2024\/02\/Dental-Implants-3-768x336.png 768w, https:\/\/florentiadent.com\/wp-content\/uploads\/2024\/02\/Dental-Implants-3-600x263.png 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31b5c7f elementor-widget elementor-widget-heading\" data-id=\"31b5c7f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 18-04-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Find out why we are the best for dental implants in Albania.<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44b80811 elementor-widget elementor-widget-text-editor\" data-id=\"44b80811\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 18-04-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"row-inner\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column wpb_content_element\"><div class=\"wpb_wrapper\"><p>A dental implant is the artificial root of the tooth. During implantation, the implant is screwed into the jawbone. Replaces the missing natural tooth root. An artificial tooth, called a dental crown, is screwed into place when the implant is attached.<\/p><p>Loss of dental implants allows us to restore the tooth root and perform dentures without damaging adjacent teeth. The prosthesis restores 80% of masticatory function. The patient can thoroughly chew soft and hard foods but should avoid fine foods, such as fried bread and nuts.<\/p><p>Implants support an artificial crown or dental bridge in the same way that roots hold a tooth in place. Dental implants help restore lost teeth without damaging nearby teeth. Implants can restore a single tooth or the entire toothless jaw.<\/p><p>I nostro impianti ImplantSwiss sono prodotti svizzeri , approvati da CE e FDA, accompagnati con CERTIFICATO DI GARANZIA A VITA!<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-834f05 elementor-widget elementor-widget-mediaxsectiontitle\" data-id=\"834f05\" data-element_type=\"widget\" data-widget_type=\"mediaxsectiontitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"title-area text-left\">\r\n\t\t\t<span class=\"sub-title\"><img decoding=\"async\" src=\"https:\/\/florentiadent.com\/wp-content\/plugins\/mediax-core\/assets\/img\/title_icon.svg\" alt=\"Shape\">THE DENTAL IMPLANT PROCEDURE INCLUDES THE FOLLOWING MAIN PHASES:<\/span>\t\t<\/div>\r\n\r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50469e1 elementor-widget elementor-widget-mediaxfeatures\" data-id=\"50469e1\" data-element_type=\"widget\" data-widget_type=\"mediaxfeatures.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"achieve-box-wrap\"><div class=\"achieve-box hover-item\"><div class=\"box-year\">1<\/div><div class=\"media-body\"><p class=\"box-text\">Consultation and preparation of a treatment plan.<\/p><\/div><\/div><div class=\"achieve-box hover-item item-active\"><div class=\"box-year\">2<\/div><div class=\"media-body\"><p class=\"box-text\">Temporary implants and prostheses.<\/p><\/div><\/div><div class=\"achieve-box hover-item\"><div class=\"box-year\">3<\/div><div class=\"media-body\"><p class=\"box-text\">\nPeriodic check<\/p><\/div><\/div><div class=\"achieve-box hover-item\"><div class=\"box-year\">4<\/div><div class=\"media-body\"><p class=\"box-text\">Permanent coronal prosthesis on implants.<\/p><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>IMPIANTI DENTALI Tutti i Servizi Impianti Dentali Corone Dentali Protesi Dentaria Allineatori Invisalign Chirurgia Orale e Maxillo-Facciale Estetica Creiamo Bellissimi Sorrisi Compila il modulo sottostante per un preventivo gratuito! Prenotare un appuntamento Scegli OggettoOttieni un preventivoConsulenza Gratuita INVIA LA TUA RICHIESTA Scopri perch\u00e9 siamo i migliori per gli impianti dentali in Albania. Un impianto dentale&#8230;<\/p>","protected":false},"author":1,"featured_media":2191,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2488","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Impianti Dentali - Florentia Dent - Turismo Dentale in Albnaia<\/title>\n<meta name=\"description\" content=\"Impianti Dentali in Albania. Complessivamente il successo degli impianti \u00e8 del 98%, e se l&#039;igiene orale e la pulizia periodica del dentista sono regolari possono durare tutta la vita.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/florentiadent.com\/en\/impianti-dentali\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impianti Dentali - Florentia Dent - Turismo Dentale in Albnaia\" \/>\n<meta property=\"og:description\" content=\"Impianti Dentali in Albania. Complessivamente il successo degli impianti \u00e8 del 98%, e se l&#039;igiene orale e la pulizia periodica del dentista sono regolari possono durare tutta la vita.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/florentiadent.com\/en\/impianti-dentali\/\" \/>\n<meta property=\"og:site_name\" content=\"Florentia Dent - Turismo Dentale in Albnaia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.instagram.com\/florentiadent___dentaltourism\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-28T18:28:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/florentiadent.com\/wp-content\/uploads\/2024\/02\/Dental-Implants-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/florentiadent.com\/impianti-dentali\/\",\"url\":\"https:\/\/florentiadent.com\/impianti-dentali\/\",\"name\":\"Impianti Dentali - Florentia Dent - Turismo Dentale in Albnaia\",\"isPartOf\":{\"@id\":\"https:\/\/florentiadent.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/florentiadent.com\/impianti-dentali\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/florentiadent.com\/impianti-dentali\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/florentiadent.com\/wp-content\/uploads\/2024\/02\/Dental-Implants-3.png\",\"datePublished\":\"2024-02-09T10:44:08+00:00\",\"dateModified\":\"2024-02-28T18:28:24+00:00\",\"description\":\"Impianti Dentali in Albania. Complessivamente il successo degli impianti \u00e8 del 98%, e se l'igiene orale e la pulizia periodica del dentista sono regolari possono durare tutta la vita.\",\"breadcrumb\":{\"@id\":\"https:\/\/florentiadent.com\/impianti-dentali\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/florentiadent.com\/impianti-dentali\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/florentiadent.com\/impianti-dentali\/#primaryimage\",\"url\":\"https:\/\/florentiadent.com\/wp-content\/uploads\/2024\/02\/Dental-Implants-3.png\",\"contentUrl\":\"https:\/\/florentiadent.com\/wp-content\/uploads\/2024\/02\/Dental-Implants-3.png\",\"width\":800,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/florentiadent.com\/impianti-dentali\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/florentiadent.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impianti Dentali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/florentiadent.com\/#website\",\"url\":\"https:\/\/florentiadent.com\/\",\"name\":\"Florentia Dent - Turismo Dentale in Albnaia\",\"description\":\"Dental Turismo in Albania - Dental Tourism Albania - Implanti Dental in Albania\",\"publisher\":{\"@id\":\"https:\/\/florentiadent.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/florentiadent.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/florentiadent.com\/#organization\",\"name\":\"Turismo Dentale in Albnaia - Dental Turismo in Albania\",\"url\":\"https:\/\/florentiadent.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/florentiadent.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/florentiadent.com\/wp-content\/uploads\/2023\/12\/Florentia-Dent-Logo.png\",\"contentUrl\":\"https:\/\/florentiadent.com\/wp-content\/uploads\/2023\/12\/Florentia-Dent-Logo.png\",\"width\":180,\"height\":68,\"caption\":\"Turismo Dentale in Albnaia - Dental Turismo in Albania\"},\"image\":{\"@id\":\"https:\/\/florentiadent.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/florentiadent___dentaltourism\",\"https:\/\/www.facebook.com\/florentiadentdentaltourism?mibextid=uzlsIk\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impianti Dentali - Florentia Dent - Turismo Dentale in Albnaia","description":"Impianti Dentali in Albania. Complessivamente il successo degli impianti \u00e8 del 98%, e se l'igiene orale e la pulizia periodica del dentista sono regolari possono durare tutta la vita.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/florentiadent.com\/en\/impianti-dentali\/","og_locale":"en_US","og_type":"article","og_title":"Impianti Dentali - Florentia Dent - Turismo Dentale in Albnaia","og_description":"Impianti Dentali in Albania. Complessivamente il successo degli impianti \u00e8 del 98%, e se l'igiene orale e la pulizia periodica del dentista sono regolari possono durare tutta la vita.","og_url":"https:\/\/florentiadent.com\/en\/impianti-dentali\/","og_site_name":"Florentia Dent - Turismo Dentale in Albnaia","article_publisher":"https:\/\/www.instagram.com\/florentiadent___dentaltourism","article_modified_time":"2024-02-28T18:28:24+00:00","og_image":[{"width":800,"height":350,"url":"https:\/\/florentiadent.com\/wp-content\/uploads\/2024\/02\/Dental-Implants-3.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/florentiadent.com\/impianti-dentali\/","url":"https:\/\/florentiadent.com\/impianti-dentali\/","name":"Impianti Dentali - Florentia Dent - Turismo Dentale in Albnaia","isPartOf":{"@id":"https:\/\/florentiadent.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/florentiadent.com\/impianti-dentali\/#primaryimage"},"image":{"@id":"https:\/\/florentiadent.com\/impianti-dentali\/#primaryimage"},"thumbnailUrl":"https:\/\/florentiadent.com\/wp-content\/uploads\/2024\/02\/Dental-Implants-3.png","datePublished":"2024-02-09T10:44:08+00:00","dateModified":"2024-02-28T18:28:24+00:00","description":"Impianti Dentali in Albania. Complessivamente il successo degli impianti \u00e8 del 98%, e se l'igiene orale e la pulizia periodica del dentista sono regolari possono durare tutta la vita.","breadcrumb":{"@id":"https:\/\/florentiadent.com\/impianti-dentali\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/florentiadent.com\/impianti-dentali\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/florentiadent.com\/impianti-dentali\/#primaryimage","url":"https:\/\/florentiadent.com\/wp-content\/uploads\/2024\/02\/Dental-Implants-3.png","contentUrl":"https:\/\/florentiadent.com\/wp-content\/uploads\/2024\/02\/Dental-Implants-3.png","width":800,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/florentiadent.com\/impianti-dentali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/florentiadent.com\/"},{"@type":"ListItem","position":2,"name":"Impianti Dentali"}]},{"@type":"WebSite","@id":"https:\/\/florentiadent.com\/#website","url":"https:\/\/florentiadent.com\/","name":"Florentia Dent - Turismo Dentale in Albnaia","description":"Dental Turismo in Albania - Dental Tourism Albania - Implanti Dental in Albania","publisher":{"@id":"https:\/\/florentiadent.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/florentiadent.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/florentiadent.com\/#organization","name":"Turismo Dentale in Albnaia - Dental Turismo in Albania","url":"https:\/\/florentiadent.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/florentiadent.com\/#\/schema\/logo\/image\/","url":"https:\/\/florentiadent.com\/wp-content\/uploads\/2023\/12\/Florentia-Dent-Logo.png","contentUrl":"https:\/\/florentiadent.com\/wp-content\/uploads\/2023\/12\/Florentia-Dent-Logo.png","width":180,"height":68,"caption":"Turismo Dentale in Albnaia - Dental Turismo in Albania"},"image":{"@id":"https:\/\/florentiadent.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/florentiadent___dentaltourism","https:\/\/www.facebook.com\/florentiadentdentaltourism?mibextid=uzlsIk"]}]}},"_links":{"self":[{"href":"https:\/\/florentiadent.com\/en\/wp-json\/wp\/v2\/pages\/2488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/florentiadent.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/florentiadent.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/florentiadent.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/florentiadent.com\/en\/wp-json\/wp\/v2\/comments?post=2488"}],"version-history":[{"count":63,"href":"https:\/\/florentiadent.com\/en\/wp-json\/wp\/v2\/pages\/2488\/revisions"}],"predecessor-version":[{"id":3277,"href":"https:\/\/florentiadent.com\/en\/wp-json\/wp\/v2\/pages\/2488\/revisions\/3277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/florentiadent.com\/en\/wp-json\/wp\/v2\/media\/2191"}],"wp:attachment":[{"href":"https:\/\/florentiadent.com\/en\/wp-json\/wp\/v2\/media?parent=2488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}